{"id":2593,"date":"2023-07-15T12:29:12","date_gmt":"2023-07-15T15:29:12","guid":{"rendered":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/"},"modified":"2023-07-15T12:29:12","modified_gmt":"2023-07-15T15:29:12","slug":"pl-1637-2007","status":"publish","type":"page","link":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/","title":{"rendered":"PL 1637\/2007"},"content":{"rendered":"<h1 style='text-align: center;'>C\u00e2mara &#8211; Autoria de CARLOS GOMES BEZERRA<br \/><img src='https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg' alt='CARLOS GOMES BEZERRA' \/><\/h3>\n<p><\/p>\n<article>Disp\u00f5e sobre oferta, propaganda, publicidade, informa\u00e7\u00e3o e outras pr\u00e1ticas correlatas, cujo objeto seja a divulga\u00e7\u00e3o e a promo\u00e7\u00e3o de alimentos com quantidades elevadas de a\u00e7\u00facar, de gordura saturada, de gordura trans, de s\u00f3dio, e de bebidas com baixo teor nutricional.<\/article>\n<p><a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=Restri\u00e7\u00e3o'>Restri\u00e7\u00e3o<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=publicidade'>publicidade<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=propaganda comercial'>propaganda comercial<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=alimentos'>alimentos<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=composi\u00e7\u00e3o'>composi\u00e7\u00e3o<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=a\u00e7\u00facar'>a\u00e7\u00facar<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=gordura'>gordura<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=s\u00f3dio'>s\u00f3dio<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=obrigatoriedade'>obrigatoriedade<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=inclus\u00e3o'>inclus\u00e3o<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=mensagem'>mensagem<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=advert\u00eancia'>advert\u00eancia<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=limita\u00e7\u00e3o'>limita\u00e7\u00e3o<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=hor\u00e1rio'>hor\u00e1rio<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=divulga\u00e7\u00e3o'>divulga\u00e7\u00e3o<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=emissora'>emissora<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=televis\u00e3o'>televis\u00e3o<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=proibi\u00e7\u00e3o'>proibi\u00e7\u00e3o<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=pr\u00eamio'>pr\u00eamio<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=propaganda enganosa'>propaganda enganosa<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=benef\u00edcio'>benef\u00edcio<\/a>, <a href='https:\/\/app.legislapp.com.br\/#\/busca?termo=sa\u00fade.'>sa\u00fade.<\/a><\/p>\n<div style=\"text-align: center\">\n      <img decoding=\"async\" style=\"width: 14%;\" src=\"https:\/\/legislapp.com.br\/wp-content\/uploads\/2021\/07\/Logo-Legislapp-1-03-1.png\"><br \/>\n      <\/p>\n<div style=\"margin-bottom: 20px;\" class=\"et_pb_button_module_wrapper et_pb_button_5_tb_body_wrapper et_pb_button_alignment_center et_pb_module \">\n         <a class=\"et_pb_button et_pb_button_5_tb_body et_hover_enabled et_pb_bg_layout_dark\" style=\"width: 50%;background-color: black;\" href=\"https:\/\/app.legislapp.com.br\" target=\"_blank\" rel=\"noopener\">Visualizar completo na nossa plataforma (30 dias gr\u00e1tis)<\/a><\/p><\/div>\n<p>      <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=br.com.legislapp\"><img decoding=\"async\" style=\"width: 15%; min-width: 130px;\" src=\"https:\/\/legislapp.com.br\/wp-content\/uploads\/google-play.png\"><\/a><br \/>\n      <a href=\"https:\/\/apps.apple.com\/us\/app\/legislapp\/id1568929859\"><img decoding=\"async\" style=\"width: 15%; min-width: 130px\" src=\"https:\/\/legislapp.com.br\/wp-content\/uploads\/apple-store.png\"><\/a>\n   <\/div>\n","protected":false},"excerpt":{"rendered":"<p>C\u00e2mara &#8211; Autoria de CARLOS GOMES BEZERRA Disp\u00f5e sobre oferta, propaganda, publicidade, informa\u00e7\u00e3o e outras pr\u00e1ticas correlatas, cujo objeto seja a divulga\u00e7\u00e3o e a promo\u00e7\u00e3o de alimentos com quantidades elevadas de a\u00e7\u00facar, de gordura saturada, de gordura trans, de s\u00f3dio, e de bebidas com baixo teor nutricional. Restri\u00e7\u00e3o, publicidade, propaganda comercial, alimentos, composi\u00e7\u00e3o, a\u00e7\u00facar, gordura, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-template-blank.php","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"1080","ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2593","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PL 1637\/2007 - Legislapp<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PL 1637\/2007 - Legislapp\" \/>\n<meta property=\"og:description\" content=\"C\u00e2mara &#8211; Autoria de CARLOS GOMES BEZERRA Disp\u00f5e sobre oferta, propaganda, publicidade, informa\u00e7\u00e3o e outras pr\u00e1ticas correlatas, cujo objeto seja a divulga\u00e7\u00e3o e a promo\u00e7\u00e3o de alimentos com quantidades elevadas de a\u00e7\u00facar, de gordura saturada, de gordura trans, de s\u00f3dio, e de bebidas com baixo teor nutricional. Restri\u00e7\u00e3o, publicidade, propaganda comercial, alimentos, composi\u00e7\u00e3o, a\u00e7\u00facar, gordura, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/\" \/>\n<meta property=\"og:site_name\" content=\"Legislapp\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/legislapp\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/\",\"url\":\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/\",\"name\":\"PL 1637\/2007 - Legislapp\",\"isPartOf\":{\"@id\":\"https:\/\/www.legislapp.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg\",\"datePublished\":\"2023-07-15T15:29:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#primaryimage\",\"url\":\"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg\",\"contentUrl\":\"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.legislapp.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PL 1637\/2007\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legislapp.com.br\/#website\",\"url\":\"https:\/\/www.legislapp.com.br\/\",\"name\":\"Legislapp\",\"description\":\"Intelig\u00eancia governamental em tempo real\",\"publisher\":{\"@id\":\"https:\/\/www.legislapp.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legislapp.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.legislapp.com.br\/#organization\",\"name\":\"Legislapp Monitoramento e Intelig\u00eancia Governamental\",\"url\":\"https:\/\/www.legislapp.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.legislapp.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.legislapp.com.br\/wp-content\/uploads\/icon.png\",\"contentUrl\":\"https:\/\/www.legislapp.com.br\/wp-content\/uploads\/icon.png\",\"width\":1024,\"height\":1024,\"caption\":\"Legislapp Monitoramento e Intelig\u00eancia Governamental\"},\"image\":{\"@id\":\"https:\/\/www.legislapp.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/legislapp\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PL 1637\/2007 - Legislapp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/","og_locale":"pt_BR","og_type":"article","og_title":"PL 1637\/2007 - Legislapp","og_description":"C\u00e2mara &#8211; Autoria de CARLOS GOMES BEZERRA Disp\u00f5e sobre oferta, propaganda, publicidade, informa\u00e7\u00e3o e outras pr\u00e1ticas correlatas, cujo objeto seja a divulga\u00e7\u00e3o e a promo\u00e7\u00e3o de alimentos com quantidades elevadas de a\u00e7\u00facar, de gordura saturada, de gordura trans, de s\u00f3dio, e de bebidas com baixo teor nutricional. Restri\u00e7\u00e3o, publicidade, propaganda comercial, alimentos, composi\u00e7\u00e3o, a\u00e7\u00facar, gordura, [&hellip;]","og_url":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/","og_site_name":"Legislapp","article_publisher":"https:\/\/www.instagram.com\/legislapp\/","og_image":[{"url":"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/","url":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/","name":"PL 1637\/2007 - Legislapp","isPartOf":{"@id":"https:\/\/www.legislapp.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#primaryimage"},"image":{"@id":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#primaryimage"},"thumbnailUrl":"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg","datePublished":"2023-07-15T15:29:12+00:00","breadcrumb":{"@id":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#primaryimage","url":"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg","contentUrl":"https:\/\/www.camara.leg.br\/internet\/deputado\/bandep\/141401.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.legislapp.com.br\/index.php\/pl-1637-2007\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.legislapp.com.br\/"},{"@type":"ListItem","position":2,"name":"PL 1637\/2007"}]},{"@type":"WebSite","@id":"https:\/\/www.legislapp.com.br\/#website","url":"https:\/\/www.legislapp.com.br\/","name":"Legislapp","description":"Intelig\u00eancia governamental em tempo real","publisher":{"@id":"https:\/\/www.legislapp.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legislapp.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.legislapp.com.br\/#organization","name":"Legislapp Monitoramento e Intelig\u00eancia Governamental","url":"https:\/\/www.legislapp.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.legislapp.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/www.legislapp.com.br\/wp-content\/uploads\/icon.png","contentUrl":"https:\/\/www.legislapp.com.br\/wp-content\/uploads\/icon.png","width":1024,"height":1024,"caption":"Legislapp Monitoramento e Intelig\u00eancia Governamental"},"image":{"@id":"https:\/\/www.legislapp.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/legislapp\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.legislapp.com.br\/index.php\/wp-json\/wp\/v2\/pages\/2593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legislapp.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.legislapp.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.legislapp.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legislapp.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2593"}],"version-history":[{"count":0,"href":"https:\/\/www.legislapp.com.br\/index.php\/wp-json\/wp\/v2\/pages\/2593\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legislapp.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}